{"id":19044,"date":"2026-02-20T15:41:20","date_gmt":"2026-02-20T15:41:20","guid":{"rendered":"https:\/\/foodlabelmaker.com\/regulatory-hub\/%regulatory-category%\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/"},"modified":"2026-02-23T13:12:05","modified_gmt":"2026-02-23T13:12:05","slug":"guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz","status":"publish","type":"regulatory-hub","link":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/","title":{"rendered":"Gu\u00eda completa del panel de informaci\u00f3n nutricional (NIP) de FSANZ"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Comprender el cumplimiento alimentario en Australia y Nueva Zelanda comienza con el panel de informaci\u00f3n nutricional (NIP). Esta gu\u00eda proporciona una visi\u00f3n general de los requisitos obligatorios y explica la importancia de cada nutriente para ayudarle a crear una etiqueta nutricional que sea conforme e informativa. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>De un vistazo: paneles de informaci\u00f3n nutricional de FSANZ<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Nutrientes obligatorios:<\/strong> Todos los NIP deben incluir energ\u00eda (en kJ), prote\u00ednas, grasas totales, grasas saturadas, hidratos de carbono, az\u00facares y sodio.<\/li>\n\n\n\n<li><strong>Columnas dobles:<\/strong> Debe mostrar las cantidades \u00abpor porci\u00f3n\u00bb y \u00abpor 100 g\u00bb (o 100 ml para l\u00edquidos).<\/li>\n\n\n\n<li><strong>Norma 1.2.8:<\/strong> Esta es la normativa principal del C\u00f3digo de Normas Alimentarias que regula el etiquetado nutricional en Australia y Nueva Zelanda.<\/li>\n\n\n\n<li><strong>Exenciones:<\/strong> Algunos productos, como el agua natural, las especias o los envases muy peque\u00f1os, pueden estar exentos de llevar un NIP.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">\u00bfListo para empezar? Utilice nuestra <a href=\"https:\/\/foodlabelmaker.com\/es-mx\/\">plantilla de panel nutricional de FSANZ<\/a> para generar una etiqueta conforme en minutos. <\/p>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #0f393a;color:#0f393a\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #0f393a;color:#0f393a\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#Introduccion_por_que_es_importante_el_NIP\" >Introducci\u00f3n: por qu\u00e9 es importante el NIP<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#%C2%BFQue_alimentos_deben_llevar_un_panel_de_informacion_nutricional_NIP\" >\u00bfQu\u00e9 alimentos deben llevar un panel de informaci\u00f3n nutricional (NIP)?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#%C2%BFQue_contiene_un_panel_de_informacion_nutricional\" >\u00bfQu\u00e9 contiene un panel de informaci\u00f3n nutricional?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#Componentes_del_panel_de_informacion_nutricional\" >Componentes del panel de informaci\u00f3n nutricional<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#Formato_y_estilo\" >Formato y estilo<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#Requisitos_adicionales_de_etiquetado_nutricional_en_Australia_y_Nueva_Zelanda\" >Requisitos adicionales de etiquetado nutricional en Australia y Nueva Zelanda<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#Declaraciones_de_contenido_nutricional\" >Declaraciones de contenido nutricional<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#El_sistema_Health_Star_Rating_HSR\" >El sistema Health Star Rating (HSR)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#Otros_elementos_obligatorios_de_la_etiqueta\" >Otros elementos obligatorios de la etiqueta<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#Como_generar_un_panel_de_informacion_nutricional_conforme\" >C\u00f3mo generar un panel de informaci\u00f3n nutricional conforme<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#Preguntas_frecuentes_sobre_los_paneles_de_informacion_nutricional\" >Preguntas frecuentes sobre los paneles de informaci\u00f3n nutricional<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#%C2%BFQue_es_un_panel_de_informacion_nutricional\" >\u00bfQu\u00e9 es un panel de informaci\u00f3n nutricional?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#%C2%BFComo_se_lee_un_panel_de_informacion_nutricional\" >\u00bfC\u00f3mo se lee un panel de informaci\u00f3n nutricional?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#%C2%BFComo_se_crea_un_panel_de_informacion_nutricional_para_empresas_alimentarias_de_Australia_y_Nueva_Zelanda\" >\u00bfC\u00f3mo se crea un panel de informaci\u00f3n nutricional para empresas alimentarias de Australia y Nueva Zelanda?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-introduction-why-the-nip-matters\"><span class=\"ez-toc-section\" id=\"Introduccion_por_que_es_importante_el_NIP\"><\/span>Introducci\u00f3n: por qu\u00e9 es importante el NIP<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la normativa de FSANZ (<a href=\"https:\/\/www.foodstandards.gov.au\/sites\/default\/files\/food-standards-code\/proposals\/Documents\/P293%20Health%20Claims%20Cons%20paper%20-%20Attach%203.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Food Standards Australia New Zealand 1.2.8<\/a>), la mayor\u00eda de los alimentos envasados est\u00e1n legalmente obligados a mostrar esta tabla estandarizada para garantizar la transparencia para los consumidores. Sin embargo, el cumplimiento va m\u00e1s all\u00e1 de evitar sanciones: se trata de satisfacer las expectativas cambiantes del comprador moderno. Con m\u00e1s del <a href=\"https:\/\/www.foodstandards.gov.au\/media\/new-survey-reveals-consumer-attitudes-food-safety-australia-and-new-zealand\" target=\"_blank\" rel=\"noreferrer noopener\">70% de las personas<\/a> confiando en el etiquetado alimentario obligatorio del reverso del envase (como el panel de informaci\u00f3n nutricional y la lista de ingredientes), mantener un panel de informaci\u00f3n nutricional profesional que los compradores de Nueva Zelanda y Australia puedan leer f\u00e1cilmente proporciona una ventaja competitiva clara en un mercado saturado.  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-foods-are-required-to-have-a-nutrition-information-panel-nip\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_alimentos_deben_llevar_un_panel_de_informacion_nutricional_NIP\"><\/span>\u00bfQu\u00e9 alimentos deben llevar un panel de informaci\u00f3n nutricional (NIP)? <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de los alimentos envasados requieren un NIP, pero existen <a href=\"https:\/\/www.legislation.gov.au\/F2015L00386\/latest\/text\" target=\"_blank\" rel=\"noreferrer noopener\">exenciones espec\u00edficas<\/a> seg\u00fan las normas de cumplimiento del etiquetado de alimentos en Australia. Los siguientes no requieren paneles de informaci\u00f3n nutricional: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Alimentos elaborados y envasados en el establecimiento desde el que se venden (p. ej., una panader\u00eda).<\/li>\n\n\n\n<li>Frutas y verduras frescas <\/li>\n\n\n\n<li>Alimentos vendidos en eventos ben\u00e9ficos<\/li>\n\n\n\n<li>Alimentos listos para consumir<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-on-a-nutrition-information-panel\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_contiene_un_panel_de_informacion_nutricional\"><\/span>\u00bfQu\u00e9 contiene un panel de informaci\u00f3n nutricional?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"535\" src=\"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-1024x535.jpeg\" alt=\"Diagrama de un panel de informaci\u00f3n nutricional (NIP) conforme a FSANZ que destaca los elementos obligatorios: t\u00edtulo, informaci\u00f3n de la porci\u00f3n, columnas de comparaci\u00f3n dobles (por porci\u00f3n y por 100 g), nutrientes obligatorios (energ\u00eda, prote\u00ednas, grasas, hidratos de carbono, sodio) y energ\u00eda mostrada en kilojulios.\" class=\"wp-image-19014\" srcset=\"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-1024x535.jpeg 1024w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-300x157.jpeg 300w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-768x401.jpeg 768w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-900x470.jpeg 900w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-645x337.jpeg 645w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-420x219.jpeg 420w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-318x166.jpeg 318w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-290x152.jpeg 290w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-630x329.jpeg 630w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1-280x146.jpeg 280w, https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/image-1.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/figure>\n\n<h3 class=\"wp-block-heading\" id=\"h-components-of-the-nutrition-information-panel\"><span class=\"ez-toc-section\" id=\"Componentes_del_panel_de_informacion_nutricional\"><\/span>Componentes del panel de informaci\u00f3n nutricional<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<ul class=\"wp-block-list\">\n<li><strong>El t\u00edtulo obligatorio<\/strong>: El panel debe titularse claramente como \u00ab<strong>INFORMACI\u00d3N NUTRICIONAL<\/strong>\u00bb para que los consumidores puedan identificarlo de inmediato.<\/li>\n\n\n\n<li><strong>Informaci\u00f3n de la porci\u00f3n:<\/strong> Incluye tanto las \u00abporciones por envase\u00bb como el \u00abtama\u00f1o de la porci\u00f3n\u00bb. Los fabricantes deben definir un tama\u00f1o de porci\u00f3n realista e indicar cu\u00e1ntas de esas porciones hay en todo el envase. A diferencia de la FDA, que <a href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fda\/como-determinar-los-tamanos-de-las-porciones-segun-la-fda-en-las-etiquetas-nutricionales\/\">regula los tama\u00f1os de las porciones<\/a> para garantizar coherencia y claridad para los consumidores, FSANZ no tiene su propia <a href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fda\/descodificando-las-cantidades-de-referencia-de-consumo-habitual-racc\/\">RACC<\/a> (cantidades de referencia habitualmente consumidas) para determinar los tama\u00f1os de las porciones de los alimentos.  <\/li>\n\n\n\n<li><strong>Columnas de comparaci\u00f3n:<\/strong> Estas columnas dobles (\u00abcantidad por porci\u00f3n\u00bb y \u00abcantidad por 100 g\u00bb) son necesarias para comparar productos similares de diferentes marcas, utilizando el est\u00e1ndar de 100 g, y para que los consumidores vean exactamente lo que est\u00e1n consumiendo por porci\u00f3n.<\/li>\n\n\n\n<li><strong>Energ\u00eda (en kilojulios)<\/strong>: En Australia y Nueva Zelanda, la energ\u00eda en un panel nutricional debe presentarse en kilojulios (kJ).<\/li>\n\n\n\n<li><strong>Los macronutrientes y micronutrientes obligatorios<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Prote\u00ednas:<\/strong> Medidas en gramos.<\/li>\n\n\n\n<li><strong>Grasas (totales y saturadas):<\/strong> Las grasas totales y las grasas saturadas deben indicarse por separado para ayudar a los consumidores a controlar la salud cardiovascular.<\/li>\n\n\n\n<li><strong>Hidratos de carbono (totales y az\u00facares):<\/strong> Muestra los hidratos de carbono totales frente a la cantidad que procede espec\u00edficamente de az\u00facares (naturales o a\u00f1adidos).<\/li>\n\n\n\n<li><strong>Sodio:<\/strong> Siempre se indica en miligramos (mg) porque incluso peque\u00f1as cantidades afectan significativamente a la salud.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\" id=\"h-formatting-amp-style\"><span class=\"ez-toc-section\" id=\"Formato_y_estilo\"><\/span>Formato y estilo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Para mantener el cumplimiento, el NIP debe presentarse en el formato est\u00e1ndar en ingl\u00e9s y debe mostrarse de forma destacada y legible, lo que a menudo incluye estar enmarcado dentro de un borde distintivo para separarlo de otros elementos del dise\u00f1o del envase. <\/p>\n\n<p class=\"wp-block-paragraph\">Aunque existe cierta flexibilidad en el dise\u00f1o para envases de formas \u00fanicas, el objetivo principal es garantizar que los consumidores puedan leer claramente la informaci\u00f3n sin que quede oculta o amontonada.<\/p>\n\n<p class=\"wp-block-paragraph\">Si tiene dificultades con c\u00e1lculos complejos o normas de dise\u00f1o, <a href=\"https:\/\/foodlabelmaker.com\/es-mx\/\">pruebe nuestra calculadora de informaci\u00f3n nutricional<\/a> en la que conf\u00edan las empresas alimentarias australianas, garantizando que los tama\u00f1os de fuente y los bordes cumplan la prueba de \u00ablegibilidad\u00bb.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-additional-nutrition-labeling-requirements-in-australia-amp-nz\"><span class=\"ez-toc-section\" id=\"Requisitos_adicionales_de_etiquetado_nutricional_en_Australia_y_Nueva_Zelanda\"><\/span>Requisitos adicionales de etiquetado nutricional en Australia y Nueva Zelanda<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">Aunque el NIP es el n\u00facleo de su etiqueta, es solo una parte de un producto conforme. Los fabricantes de alimentos est\u00e1n legalmente obligados a integrar elementos de seguridad obligatorios, como las advertencias sobre al\u00e9rgenos. Tambi\u00e9n se pueden a\u00f1adir herramientas de marketing voluntarias, como las declaraciones nutricionales, pero deben cumplir normas reglamentarias espec\u00edficas para garantizar que no sean enga\u00f1osas.  <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-nutrition-content-claims\"><span class=\"ez-toc-section\" id=\"Declaraciones_de_contenido_nutricional\"><\/span><strong>Declaraciones de contenido nutricional<\/strong> <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Una de las formas m\u00e1s comunes en que las empresas mejoran sus etiquetas es mediante declaraciones de contenido nutricional voluntarias, como \u00abalto en fibra\u00bb, \u00abbuena fuente de calcio\u00bb o \u00abbajo en grasas\u00bb. Seg\u00fan la norma 1.2.7, una vez que decida hacer una declaraci\u00f3n, se vuelve obligatorio incluir ese nutriente espec\u00edfico en su NIP y cumplir los criterios prescritos para esa declaraci\u00f3n. <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-the-health-star-rating-hsr-system\"><span class=\"ez-toc-section\" id=\"El_sistema_Health_Star_Rating_HSR\"><\/span>El sistema Health Star Rating (HSR)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Durante m\u00e1s de una d\u00e9cada, el <a href=\"https:\/\/www.healthstarrating.gov.au\/\" target=\"_blank\" rel=\"noreferrer noopener\">sistema Health Star Rating<\/a> ha funcionado como una herramienta de etiquetado frontal voluntaria dise\u00f1ada para ayudar a los consumidores a comparar los perfiles nutricionales de productos similares. Sin embargo, <a href=\"https:\/\/www.healthstarrating.gov.au\/\" target=\"_blank\" rel=\"noreferrer noopener\">en febrero de 2026<\/a>, los ministros de Alimentaci\u00f3n de Australia y Nueva Zelanda acordaron formalmente iniciar el proceso para hacer obligatorio el sistema despu\u00e9s de que la adopci\u00f3n voluntaria de la industria no alcanzara el objetivo del 70%. <\/p>\n\n<p class=\"wp-block-paragraph\">Es importante se\u00f1alar que, aunque el proceso para hacerlo obligatorio ha comenzado oficialmente, el sistema HSR sigue siendo voluntario durante el per\u00edodo de transici\u00f3n actual. Food Standards Australia New Zealand (FSANZ) est\u00e1 iniciando ahora el proceso legislativo de <a href=\"https:\/\/www.theguardian.com\/australia-news\/2026\/feb\/13\/health-star-rating-packaged-food-mandatory-australia\" target=\"_blank\" rel=\"noreferrer noopener\">12 a 18 meses<\/a> para a\u00f1adir formalmente el HSR al C\u00f3digo de Normas Alimentarias. Para los fabricantes, este es un momento cr\u00edtico para garantizar que los datos de su NIP sean precisos, ya que estas cifras determinar\u00e1n directamente la calificaci\u00f3n por estrellas de su producto una vez que entre en vigor el mandato.   <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-other-mandatory-label-elements\"><span class=\"ez-toc-section\" id=\"Otros_elementos_obligatorios_de_la_etiqueta\"><\/span><strong>Otros elementos obligatorios de la etiqueta<\/strong> <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">M\u00e1s all\u00e1 de los datos nutricionales, la <strong>norma 1.2.1<\/strong> requiere varios otros elementos no negociables para la etiqueta de un producto alimentario. Esto incluye<strong>:<\/strong> <\/p>\n\n<ol class=\"wp-block-list\">\n<li><strong>Identidad del producto:<\/strong> La etiqueta debe incluir un nombre o descripci\u00f3n que indique claramente la \u00abverdadera naturaleza\u00bb del alimento para evitar enga\u00f1ar a los consumidores. Tambi\u00e9n debe incluir la identificaci\u00f3n del lote (n\u00fameros de lote) para ayudar en caso de retirada de alimentos. <\/li>\n\n\n\n<li><strong>Informaci\u00f3n de seguridad y PEAL:<\/strong> Las declaraciones obligatorias de al\u00e9rgenos ahora deben seguir las normas de <a href=\"https:\/\/www.foodstandards.gov.au\/food-standards-code\/proposals\/P1044PlainEnglishAllergenLabelling\" target=\"_blank\" rel=\"noreferrer noopener\">etiquetado de al\u00e9rgenos en ingl\u00e9s sencillo (PEAL)<\/a>. Los al\u00e9rgenos deben estar en negrita en la lista de ingredientes y repetirse en una declaraci\u00f3n separada en negrita \u00abContiene\u00bb. Otros elementos de seguridad incluyen declaraciones de advertencia (p. ej., para la cafe\u00edna) y marcado de fecha (consumir antes de o consumir preferentemente antes de).  <\/li>\n\n\n\n<li><strong>Transparencia y datos del proveedor:<\/strong> Se requiere una declaraci\u00f3n completa de ingredientes, enumerados en orden descendente por peso de entrada. Adem\u00e1s, debe incluir el nombre y la direcci\u00f3n postal f\u00edsica del proveedor en Australia o Nueva Zelanda; un apartado de correos es legalmente insuficiente para este requisito. <\/li>\n\n\n\n<li><strong>Pa\u00eds de origen:<\/strong> La mayor\u00eda de los alimentos vendidos al por menor en Australia deben mostrar una etiqueta de pa\u00eds de origen. Para los \u00abalimentos prioritarios\u00bb, esto incluye el conocido logotipo del canguro, un gr\u00e1fico de barras que muestra el porcentaje de ingredientes locales y una declaraci\u00f3n de texto de apoyo. <\/li>\n\n\n\n<li><strong>Instrucciones especiales:<\/strong> Para garantizar que el alimento permanezca seguro hasta su fecha de caducidad, debe incluir condiciones de almacenamiento espec\u00edficas (p. ej., \u00abConservar por debajo de 4 \u00b0C\u00bb) e instrucciones de uso si el alimento requiere preparaci\u00f3n antes del consumo.<\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-to-generate-a-compliant-nutrition-information-panel\"><span class=\"ez-toc-section\" id=\"Como_generar_un_panel_de_informacion_nutricional_conforme\"><\/span>C\u00f3mo generar un panel de informaci\u00f3n nutricional conforme<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p class=\"wp-block-paragraph\">Elegir el m\u00e9todo adecuado para su NIP depende de la complejidad y el presupuesto de su producto. Existen 3 enfoques principales utilizados por los fabricantes de alimentos de AU\/NZ: <\/p>\n\n<figure class=\"wp-block-table flm-header\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Caracter\u00edstica<\/strong><\/td><td><strong>An\u00e1lisis de laboratorio<\/strong><\/td><td><strong>Hoja de c\u00e1lculo (manual)<\/strong><\/td><td><strong>Software de etiquetado de alimentos (Food Label Maker)<\/strong><\/td><\/tr><tr><td><strong>Costo<\/strong><\/td><td>Alto ($500+ por prueba)<\/td><td>Gratuito<\/td><td>Bajo \/ Suscripci\u00f3n<\/td><\/tr><tr><td><strong>Velocidad<\/strong><\/td><td>2\u20134 semanas<\/td><td>Lento (entrada manual)<\/td><td>Instant\u00e1neo<\/td><\/tr><tr><td><strong>Precisi\u00f3n<\/strong><\/td><td>Alta (qu\u00edmica)<\/td><td>Baja (riesgo de error del usuario)<\/td><td>Alta (bases de datos verificadas)<\/td><\/tr><tr><td><strong>Cumplimiento<\/strong><\/td><td>Informe t\u00e9cnico<\/td><td>Formato manual<\/td><td>Plantilla FSANZ integrada<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">Un software de etiquetado de alimentos como <a href=\"https:\/\/foodlabelmaker.com\/es-mx\/\">Food Label Maker<\/a> proporciona una alternativa r\u00e1pida, fiable y rentable a las pruebas de laboratorio para todos los productos alimentarios, al tiempo que garantiza que los c\u00e1lculos sigan autom\u00e1ticamente las estrictas normas de redondeo y formato de FSANZ. La precisi\u00f3n en su NIP es m\u00e1s cr\u00edtica que nunca; a partir de febrero de 2026, el sistema Health Star Rating (HSR) ha pasado oficialmente de voluntario a obligatorio en todos los alimentos envasados en Australia y Nueva Zelanda. Dado que su calificaci\u00f3n por estrellas obligatoria se calcula directamente a partir de los datos de su NIP, cualquier error en su panel puede dar lugar a una calificaci\u00f3n incorrecta y al incumplimiento normativo.  <\/p>\n\n<p class=\"wp-block-paragraph\">Al hacer correctamente todos los elementos de la etiqueta nutricional y adelantarse a los requisitos obligatorios, las empresas alimentarias pueden posicionarse para el \u00e9xito a largo plazo en un mercado competitivo. Evite costosos errores manuales y adel\u00e1ntese a estos nuevos mandatos de 2026 descargando y siguiendo esta <a href=\"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/FSANZ-Food-Label-Compliance-Checklist.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">lista de verificaci\u00f3n para el cumplimiento de las etiquetas de FSANZ<\/a>. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-frequently-asked-questions-about-nutrition-information-panels\"><span class=\"ez-toc-section\" id=\"Preguntas_frecuentes_sobre_los_paneles_de_informacion_nutricional\"><\/span>Preguntas frecuentes sobre los paneles de informaci\u00f3n nutricional<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-what-is-a-nutrition-information-panel\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_un_panel_de_informacion_nutricional\"><\/span>\u00bfQu\u00e9 es un panel de informaci\u00f3n nutricional?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Un panel de informaci\u00f3n nutricional (NIP) es una tabla estandarizada que se encuentra en la mayor\u00eda de las etiquetas de alimentos envasados en Australia y Nueva Zelanda. Su prop\u00f3sito es proporcionar a los consumidores la cantidad promedio de energ\u00eda y nutrientes clave contenidos en el alimento. Seg\u00fan la <a href=\"https:\/\/www.foodstandards.gov.au\/food-standards-code\/legislation\" target=\"_blank\" rel=\"noreferrer noopener\">norma 1.2.8<\/a> del C\u00f3digo de Normas Alimentarias, casi todos los alimentos envasados al por menor deben mostrar esta informaci\u00f3n para ayudar a las personas a tomar decisiones diet\u00e9ticas informadas. Un NIP est\u00e1ndar debe declarar siete componentes obligatorios: energ\u00eda (en kilojulios), prote\u00ednas, grasas totales, grasas saturadas, hidratos de carbono totales, az\u00facares y sodio.   <\/p>\n\n<p class=\"wp-block-paragraph\">Para crear una etiqueta nutricional conforme a FSANZ, comience aqu\u00ed y <a href=\"https:\/\/app.foodlabelmaker.com\/?action=signup\">cree una etiqueta NIP gratuita<\/a>. Tambi\u00e9n puede <a href=\"https:\/\/foodlabelmaker.com\/es-mx\/precios\/\">ver nuestros planes de precios<\/a> o <a href=\"https:\/\/foodlabelmaker.com\/es-mx\/contratar-experto-en-etiquetado\/\">ponerse en contacto con uno de nuestros expertos en nutrici\u00f3n<\/a> si necesita ayuda con sus etiquetas nutricionales de Australia y Nueva Zelanda.  <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-do-you-read-a-nutrition-information-panel\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_se_lee_un_panel_de_informacion_nutricional\"><\/span>\u00bfC\u00f3mo se lee un panel de informaci\u00f3n nutricional?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Leer un NIP implica observar dos columnas distintas de informaci\u00f3n:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Cantidad por porci\u00f3n:<\/strong> Utilice esta columna para ver cu\u00e1nto de un nutriente est\u00e1 consumiendo realmente en una porci\u00f3n, seg\u00fan lo definido por el fabricante.<\/li>\n<\/ul>\n\n<ul class=\"wp-block-list\">\n<li><strong>Cantidad por 100 g (o 100 ml):<\/strong> Esta columna es la forma m\u00e1s eficaz de comparar diferentes marcas o productos similares. Dado que los tama\u00f1os de las porciones var\u00edan entre fabricantes, el est\u00e1ndar \u00abpor 100 g\u00bb proporciona un campo de juego equitativo para la comparaci\u00f3n. <\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Al leer, priorice buscar productos que sean m\u00e1s bajos en grasas saturadas, sodio y az\u00facares a\u00f1adidos, mientras vigila el contenido total de energ\u00eda (kJ).<\/p>\n\n<p class=\"wp-block-paragraph\">Si busca crear paneles de informaci\u00f3n nutricional conformes con las regulaciones de FSANZ, <a href=\"https:\/\/app.foodlabelmaker.com\/?action=signup\">haga clic aqu\u00ed para generar su etiqueta gratuita utilizando nuestro generador de NIP de Australia y Nueva Zelanda.<\/a><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-how-do-you-create-a-nutrition-information-panel-for-australia-and-new-zealand-food-businesses\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_se_crea_un_panel_de_informacion_nutricional_para_empresas_alimentarias_de_Australia_y_Nueva_Zelanda\"><\/span>\u00bfC\u00f3mo se crea un panel de informaci\u00f3n nutricional para empresas alimentarias de Australia y Nueva Zelanda?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Las empresas alimentarias pueden generar un NIP conforme utilizando dos m\u00e9todos principales:<\/p>\n\n<ol class=\"wp-block-list\">\n<li><strong>An\u00e1lisis de laboratorio:<\/strong> Puede enviar una muestra f\u00edsica de su producto a un laboratorio acreditado para realizar pruebas qu\u00edmicas. Esto suele ser costoso y requiere mucho intercambio para garantizar que su etiqueta de alimentos sea totalmente conforme y precisa con las regulaciones de FSANZ. <\/li>\n<\/ol>\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>C\u00e1lculo por software:<\/strong> Los fabricantes pueden utilizar valores de bases de datos verificadas para calcular el NIP en funci\u00f3n de su receta espec\u00edfica del producto. Plataformas conformes y precisas como <a href=\"https:\/\/foodlabelmaker.com\/es-mx\/\">Food Label Maker<\/a> le permiten introducir ingredientes y cantidades para generar autom\u00e1ticamente un panel que cumpla los requisitos de formato y redondeo de la norma 1.2.8. <\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\">Para empezar, <a href=\"https:\/\/app.foodlabelmaker.com\/?action=signup\">genere su NIP de FSANZ de forma gratuita<\/a> o <a href=\"https:\/\/foodlabelmaker.com\/es-mx\/precios\/\">consulte nuestros planes de precios.<\/a><\/p>\n","protected":false},"author":10,"featured_media":19039,"parent":0,"template":"","meta":{"_acf_changed":true},"regulatory-category":[367],"class_list":["post-19044","regulatory-hub","type-regulatory-hub","status-publish","has-post-thumbnail","hentry","regulatory-category-fsanz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gu\u00eda del panel de informaci\u00f3n nutricional (NIP) de FSANZ para Australia y Nueva Zelanda<\/title>\n<meta name=\"description\" content=\"Gu\u00eda de los paneles de informaci\u00f3n nutricional de FSANZ para Australia y Nueva Zelanda. Cubre los nutrientes obligatorios, los tama\u00f1os de las porciones, las actualizaciones del Health Star Rating de 2026 y c\u00f3mo generar NIP conformes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00eda completa del panel de informaci\u00f3n nutricional (NIP) de FSANZ\" \/>\n<meta property=\"og:description\" content=\"Gu\u00eda de los paneles de informaci\u00f3n nutricional de FSANZ para Australia y Nueva Zelanda. Cubre los nutrientes obligatorios, los tama\u00f1os de las porciones, las actualizaciones del Health Star Rating de 2026 y c\u00f3mo generar NIP conformes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/\" \/>\n<meta property=\"og:site_name\" content=\"Food Label Maker\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/foodlabelmaker\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T13:12:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/FSANZ-Nutritional-Panel-Blog-img.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"636\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/\"},\"author\":{\"name\":\"Mounya Sasso\",\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/#\\\/schema\\\/person\\\/095b0e566364b2b77efa40b63c02b3f2\"},\"headline\":\"Gu\u00eda completa del panel de informaci\u00f3n nutricional (NIP) de FSANZ\",\"datePublished\":\"2026-02-20T15:41:20+00:00\",\"dateModified\":\"2026-02-23T13:12:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/\"},\"wordCount\":2160,\"image\":{\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foodlabelmaker.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/FSANZ-Nutritional-Panel-Blog-img.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/\",\"url\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/\",\"name\":\"Gu\u00eda del panel de informaci\u00f3n nutricional (NIP) de FSANZ para Australia y Nueva Zelanda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foodlabelmaker.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/FSANZ-Nutritional-Panel-Blog-img.jpg\",\"datePublished\":\"2026-02-20T15:41:20+00:00\",\"dateModified\":\"2026-02-23T13:12:05+00:00\",\"description\":\"Gu\u00eda de los paneles de informaci\u00f3n nutricional de FSANZ para Australia y Nueva Zelanda. Cubre los nutrientes obligatorios, los tama\u00f1os de las porciones, las actualizaciones del Health Star Rating de 2026 y c\u00f3mo generar NIP conformes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foodlabelmaker.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/FSANZ-Nutritional-Panel-Blog-img.jpg\",\"contentUrl\":\"https:\\\/\\\/foodlabelmaker.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/FSANZ-Nutritional-Panel-Blog-img.jpg\",\"width\":700,\"height\":636,\"caption\":\"Workspace showing laptop, smartphone displaying FSANZ food label compliance checklist, printed nutrition information panel, and coffee cup on wooden desk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/fsanz\\\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regulatory Hub\",\"item\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/centro-regulatorio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gu\u00eda completa del panel de informaci\u00f3n nutricional (NIP) de FSANZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/#website\",\"url\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/\",\"name\":\"Food Label Maker\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/#\\\/schema\\\/person\\\/095b0e566364b2b77efa40b63c02b3f2\",\"name\":\"Mounya Sasso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f137a75a2c1ee4180e5c85e7b230801614934ef43a4c4be6480c1d3e345fad1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f137a75a2c1ee4180e5c85e7b230801614934ef43a4c4be6480c1d3e345fad1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f137a75a2c1ee4180e5c85e7b230801614934ef43a4c4be6480c1d3e345fad1?s=96&d=mm&r=g\",\"caption\":\"Mounya Sasso\"},\"description\":\"Mounya Sasso is a licensed dietitian and creative content strategist, with expertise in both clinical nutrition and digital marketing. As Content Manager at Food Label Maker, she oversees the platform\u2019s entire content ecosystem, ensuring all published materials are accurate, helpful, and aligned with real-world food labeling requirements across multiple markets. Her background in writing and nutrition allows her to communicate topics to a global audience of food businesses. After earning her BSc in Nutrition &amp; Dietetics, Mounya\u2019s professional career started with a clinical dietetics internship, where she gained hands-on experience in applied nutrition and evidence-based practice. She then pivoted to digital strategy, working as a copywriter for leading regional platforms like MUNCH:ON and Mumzworld.com, where she supported large-scale content initiatives and developed clear, consumer-focused food messaging. Her unique dual-expertise allows her to bridge the gap between scientific accuracy and consumer engagement, highlighting her commitment to making regulatory compliance accessible for entrepreneurs.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mounyasasso\\\/\"],\"url\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/blog\\\/author\\\/mounya-sasso\\\/\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/#organization\\\/\",\"name\":\"Food Label Maker\",\"url\":\"https:\\\/\\\/foodlabelmaker.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/foodlabelmaker.com\\\/es-mx\\\/#logo\\\/\",\"url\":\"https:\\\/\\\/foodlabelmaker.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo.svg\"},\"email\":\"support@foodlabelmaker.com\",\"telephone\":\"+1 201 942 6427\",\"foundingDate\":\"2021\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/foodlabelmaker\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/food-label-maker\\\/about\\\/\",\"https:\\\/\\\/www.facebook.com\\\/foodlabelmaker\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gu\u00eda del panel de informaci\u00f3n nutricional (NIP) de FSANZ para Australia y Nueva Zelanda","description":"Gu\u00eda de los paneles de informaci\u00f3n nutricional de FSANZ para Australia y Nueva Zelanda. Cubre los nutrientes obligatorios, los tama\u00f1os de las porciones, las actualizaciones del Health Star Rating de 2026 y c\u00f3mo generar NIP conformes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/","og_locale":"es_MX","og_type":"article","og_title":"Gu\u00eda completa del panel de informaci\u00f3n nutricional (NIP) de FSANZ","og_description":"Gu\u00eda de los paneles de informaci\u00f3n nutricional de FSANZ para Australia y Nueva Zelanda. Cubre los nutrientes obligatorios, los tama\u00f1os de las porciones, las actualizaciones del Health Star Rating de 2026 y c\u00f3mo generar NIP conformes.","og_url":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/","og_site_name":"Food Label Maker","article_publisher":"https:\/\/www.facebook.com\/foodlabelmaker\/","article_modified_time":"2026-02-23T13:12:05+00:00","og_image":[{"width":700,"height":636,"url":"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/FSANZ-Nutritional-Panel-Blog-img.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#article","isPartOf":{"@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/"},"author":{"name":"Mounya Sasso","@id":"https:\/\/foodlabelmaker.com\/es-mx\/#\/schema\/person\/095b0e566364b2b77efa40b63c02b3f2"},"headline":"Gu\u00eda completa del panel de informaci\u00f3n nutricional (NIP) de FSANZ","datePublished":"2026-02-20T15:41:20+00:00","dateModified":"2026-02-23T13:12:05+00:00","mainEntityOfPage":{"@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/"},"wordCount":2160,"image":{"@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#primaryimage"},"thumbnailUrl":"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/FSANZ-Nutritional-Panel-Blog-img.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/","url":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/","name":"Gu\u00eda del panel de informaci\u00f3n nutricional (NIP) de FSANZ para Australia y Nueva Zelanda","isPartOf":{"@id":"https:\/\/foodlabelmaker.com\/es-mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#primaryimage"},"image":{"@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#primaryimage"},"thumbnailUrl":"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/FSANZ-Nutritional-Panel-Blog-img.jpg","datePublished":"2026-02-20T15:41:20+00:00","dateModified":"2026-02-23T13:12:05+00:00","description":"Gu\u00eda de los paneles de informaci\u00f3n nutricional de FSANZ para Australia y Nueva Zelanda. Cubre los nutrientes obligatorios, los tama\u00f1os de las porciones, las actualizaciones del Health Star Rating de 2026 y c\u00f3mo generar NIP conformes.","breadcrumb":{"@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#primaryimage","url":"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/FSANZ-Nutritional-Panel-Blog-img.jpg","contentUrl":"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2026\/02\/FSANZ-Nutritional-Panel-Blog-img.jpg","width":700,"height":636,"caption":"Workspace showing laptop, smartphone displaying FSANZ food label compliance checklist, printed nutrition information panel, and coffee cup on wooden desk"},{"@type":"BreadcrumbList","@id":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/fsanz\/guia-completa-del-panel-de-informacion-nutricional-nip-de-fsanz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/foodlabelmaker.com\/es-mx\/"},{"@type":"ListItem","position":2,"name":"Regulatory Hub","item":"https:\/\/foodlabelmaker.com\/es-mx\/centro-regulatorio\/"},{"@type":"ListItem","position":3,"name":"Gu\u00eda completa del panel de informaci\u00f3n nutricional (NIP) de FSANZ"}]},{"@type":"WebSite","@id":"https:\/\/foodlabelmaker.com\/es-mx\/#website","url":"https:\/\/foodlabelmaker.com\/es-mx\/","name":"Food Label Maker","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foodlabelmaker.com\/es-mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/foodlabelmaker.com\/es-mx\/#\/schema\/person\/095b0e566364b2b77efa40b63c02b3f2","name":"Mounya Sasso","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9f137a75a2c1ee4180e5c85e7b230801614934ef43a4c4be6480c1d3e345fad1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f137a75a2c1ee4180e5c85e7b230801614934ef43a4c4be6480c1d3e345fad1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f137a75a2c1ee4180e5c85e7b230801614934ef43a4c4be6480c1d3e345fad1?s=96&d=mm&r=g","caption":"Mounya Sasso"},"description":"Mounya Sasso is a licensed dietitian and creative content strategist, with expertise in both clinical nutrition and digital marketing. As Content Manager at Food Label Maker, she oversees the platform\u2019s entire content ecosystem, ensuring all published materials are accurate, helpful, and aligned with real-world food labeling requirements across multiple markets. Her background in writing and nutrition allows her to communicate topics to a global audience of food businesses. After earning her BSc in Nutrition &amp; Dietetics, Mounya\u2019s professional career started with a clinical dietetics internship, where she gained hands-on experience in applied nutrition and evidence-based practice. She then pivoted to digital strategy, working as a copywriter for leading regional platforms like MUNCH:ON and Mumzworld.com, where she supported large-scale content initiatives and developed clear, consumer-focused food messaging. Her unique dual-expertise allows her to bridge the gap between scientific accuracy and consumer engagement, highlighting her commitment to making regulatory compliance accessible for entrepreneurs.","sameAs":["https:\/\/www.linkedin.com\/in\/mounyasasso\/"],"url":"https:\/\/foodlabelmaker.com\/es-mx\/blog\/author\/mounya-sasso\/"},{"@type":"Organization","@id":"https:\/\/foodlabelmaker.com\/es-mx\/#organization\/","name":"Food Label Maker","url":"https:\/\/foodlabelmaker.com\/","logo":{"@type":"ImageObject","@id":"https:\/\/foodlabelmaker.com\/es-mx\/#logo\/","url":"https:\/\/foodlabelmaker.com\/wp-content\/uploads\/2022\/12\/logo.svg"},"email":"support@foodlabelmaker.com","telephone":"+1 201 942 6427","foundingDate":"2021","sameAs":["https:\/\/www.instagram.com\/foodlabelmaker\/","https:\/\/www.linkedin.com\/company\/food-label-maker\/about\/","https:\/\/www.facebook.com\/foodlabelmaker\/"]}]}},"_links":{"self":[{"href":"https:\/\/foodlabelmaker.com\/es-mx\/wp-json\/wp\/v2\/regulatory-hub\/19044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foodlabelmaker.com\/es-mx\/wp-json\/wp\/v2\/regulatory-hub"}],"about":[{"href":"https:\/\/foodlabelmaker.com\/es-mx\/wp-json\/wp\/v2\/types\/regulatory-hub"}],"author":[{"embeddable":true,"href":"https:\/\/foodlabelmaker.com\/es-mx\/wp-json\/wp\/v2\/users\/10"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foodlabelmaker.com\/es-mx\/wp-json\/wp\/v2\/media\/19039"}],"wp:attachment":[{"href":"https:\/\/foodlabelmaker.com\/es-mx\/wp-json\/wp\/v2\/media?parent=19044"}],"wp:term":[{"taxonomy":"regulatory-category","embeddable":true,"href":"https:\/\/foodlabelmaker.com\/es-mx\/wp-json\/wp\/v2\/regulatory-category?post=19044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}